{"id":40923,"date":"2022-04-02T12:00:00","date_gmt":"2022-04-02T11:00:00","guid":{"rendered":"https:\/\/www.avanet.com\/blog\/fin-de-la-venta-de-hardware-y-licencias-de-utm\/"},"modified":"2022-07-22T10:36:23","modified_gmt":"2022-07-22T09:36:23","slug":"fin-de-la-venta-de-hardware-y-licencias-de-utm","status":"publish","type":"post","link":"https:\/\/www.avanet.com\/es\/blog\/fin-de-la-venta-de-hardware-y-licencias-de-utm\/","title":{"rendered":"Fin de la venta de hardware SG y licencias UTM"},"content":{"rendered":"\n<p>Esta noticia no deber\u00eda sorprender a muchos de nuestros clientes y lectores. La cuenta atr\u00e1s para la UTM lleva bastante tiempo en marcha para nosotros y ha llegado a 0 el 2 de abril.<\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Hemos elegido deliberadamente el 2 de abril para publicar este post para que nadie piense que es una broma del d\u00eda de los inocentes. \ud83d\ude05<\/p><\/blockquote>\n\n<p>Ya anunciamos el <a href=\"https:\/\/www.avanet.com\/es\/blog\/sophos-utm-fin-de-soporte-a-finales-de-2021\/\">fin del soporte de UTM<\/a> a principios de 2021 y ahora cerramos finalmente este cap\u00edtulo retirando todos los productos relacionados de nuestro sitio web.<\/p>\n\n<p>Me ahorrar\u00e9 aqu\u00ed cualquier palabra de nostalgia por la UTM. S\u00e9 que todav\u00eda hay muchos fans ac\u00e9rrimos que siguen adorando el sistema y yo fui una vez uno de ellos. Sin embargo, los tiempos y las necesidades han cambiado y el enfoque de Sophos ha sido realmente diferente durante a\u00f1os. Por ello, el sistema operativo UTM ya no se desarrolla, sino que s\u00f3lo se mantiene.<\/p>\n\n<p>Hace a\u00f1os que empezamos a guiar a nuestros clientes hacia el nuevo camino de Sophos y migramos muchos cortafuegos SG a XG o recientemente a XGS.<\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><strong>Importante<\/strong>: Por supuesto, no dejamos de lado a nuestros clientes actuales que a\u00fan utilizan un cortafuegos SG y no han querido migrar a un cortafuegos XGS. Si lo solicita, estaremos encantados de ampliar las licencias con Sophos hasta el final. \ud83d\ude1d<\/p><\/blockquote>\n\n<p>Por \u00faltimo, me gustar\u00eda subrayar una vez m\u00e1s que s\u00f3lo nosotros, como Avanet, ya no ofrecemos hardware SG ni licencias UTM. La propia Sophos sigue listando estos productos, el producto seguramente funcionar\u00e1 hasta finales de 2025 y probablemente algunos a\u00f1os m\u00e1s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta noticia no deber\u00eda sorprender a muchos de nuestros clientes y lectores. La cuenta atr\u00e1s para la UTM lleva bastante tiempo en marcha para nosotros y ha llegado a 0 el 2 de abril. Hemos elegido deliberadamente el 2 de abril para publicar este post para que nadie piense que es una broma del d\u00eda [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":40871,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[390],"tags":[],"class_list":["post-40923","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar"],"blocksy_meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.avanet.com\/es\/wp-json\/wp\/v2\/posts\/40923","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.avanet.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.avanet.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.avanet.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.avanet.com\/es\/wp-json\/wp\/v2\/comments?post=40923"}],"version-history":[{"count":0,"href":"https:\/\/www.avanet.com\/es\/wp-json\/wp\/v2\/posts\/40923\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.avanet.com\/es\/wp-json\/wp\/v2\/media\/40871"}],"wp:attachment":[{"href":"https:\/\/www.avanet.com\/es\/wp-json\/wp\/v2\/media?parent=40923"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.avanet.com\/es\/wp-json\/wp\/v2\/categories?post=40923"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.avanet.com\/es\/wp-json\/wp\/v2\/tags?post=40923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}